{"id":2013,"date":"2021-06-16T12:13:58","date_gmt":"2021-06-16T12:13:58","guid":{"rendered":"http:\/\/34.69.47.19:81\/cardeto\/?post_type=piano_anticorruzione&#038;p=2013"},"modified":"2022-02-17T17:30:36","modified_gmt":"2022-02-17T17:30:36","slug":"piano-triennale-di-prevenzione-della-corruzione-p-t-c-p-triennio-2014-2016","status":"publish","type":"piano_anticorruzione","link":"http:\/\/2.114.201.122\/comunecardeto.it\/piano_anticorruzione\/piano-triennale-di-prevenzione-della-corruzione-p-t-c-p-triennio-2014-2016\/","title":{"rendered":"PIANO TRIENNALE DI PREVENZIONE DELLA CORRUZIONE (P.T.C.P.) TRIENNIO 2014-2016"},"content":{"rendered":"<a href=\"http:\/\/2.114.201.122\/comunecardeto.it\/wp-content\/uploads\/2021\/06\/PIANO_ANTICORRUZZIONE__CARDETO_2014-2016_ALLEGATI_1_E_2-1.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\"  data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">PIANO_ANTICORRUZZIONE__CARDETO_2014-2016_ALLEGATI_1_E_2-1<br\/><\/a>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":1654,"template":"","_links":{"self":[{"href":"http:\/\/2.114.201.122\/comunecardeto.it\/wp-json\/wp\/v2\/piano_anticorruzione\/2013"}],"collection":[{"href":"http:\/\/2.114.201.122\/comunecardeto.it\/wp-json\/wp\/v2\/piano_anticorruzione"}],"about":[{"href":"http:\/\/2.114.201.122\/comunecardeto.it\/wp-json\/wp\/v2\/types\/piano_anticorruzione"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/2.114.201.122\/comunecardeto.it\/wp-json\/wp\/v2\/media\/1654"}],"wp:attachment":[{"href":"http:\/\/2.114.201.122\/comunecardeto.it\/wp-json\/wp\/v2\/media?parent=2013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}